{"id":4002,"date":"2022-08-10T10:50:50","date_gmt":"2022-08-10T20:50:50","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=appel-a-projets&#038;p=4002"},"modified":"2022-08-10T10:59:37","modified_gmt":"2022-08-10T20:59:37","slug":"aap-samuel-de-champlain-2022-2023","status":"publish","type":"appel-a-projets","link":"https:\/\/recherche.upf.pf\/ty\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/","title":{"rendered":"FRQ &#8211; Programme Samuel-De-Champlain 2023-2024"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ty\">D\u00e9sol\u00e9, ce contenu est uniquement disponible en <a href=\"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/appel-a-projets\/4002\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p><p class=\"wp-block-paragraph\">Ce <a href=\"https:\/\/frq.gouv.qc.ca\/programme\/programme-samuel-de-champlain-2023-2024\/#objectifs\" target=\"_blank\" rel=\"noreferrer noopener\">programme<\/a> est lanc\u00e9 par les Fonds de Recherche du Qu\u00e9bec (FRQ) et s\u2019adresse aux enseignants-chercheurs de toutes les disciplines.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Objectifs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Programme a pour objectif de contribuer \u00e0 l\u2019excellence de la coop\u00e9ration universitaire et scientifique franco-qu\u00e9b\u00e9coise, \u00e0 son d\u00e9veloppement et \u00e0 sa diffusion.&nbsp;<strong>Une attention particuli\u00e8re sera port\u00e9e aux projets ciblant l\u2019amor\u00e7age de nouvelles collaborations<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Programme vise \u00e0 soutenir la mobilit\u00e9 entre la France et le Qu\u00e9bec, afin de :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Faire \u00e9merger des partenariats interuniversitaires strat\u00e9giques entre la France et le Qu\u00e9bec autour de p\u00f4les d\u2019excellence en formation ou en recherche;<\/li><li>Soutenir l\u2019amor\u00e7age de collaborations d\u2019\u00e9quipes \u00e0 haut potentiel, tant en France qu\u2019au Qu\u00e9bec;<\/li><li>Soutenir des projets novateurs qui ont un effet structurant et qui pr\u00e9sentent des perspectives int\u00e9ressantes \u00e0 long terme;<\/li><li>Favoriser l\u2019insertion des universit\u00e9s fran\u00e7aises et qu\u00e9b\u00e9coises dans les r\u00e9seaux internationaux de recherche et de formation.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le Programme se d\u00e9cline en deux volets :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Volet Recherche<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ce volet soutient la mobilit\u00e9 des chercheuses et chercheurs en vue de collaborations \u00e9mergentes et structurantes \u00e0 long terme. Il soutient \u00e9galement la mobilit\u00e9 \u00e9tudiante aux cycles sup\u00e9rieurs (master\/ma\u00eetrise et doctorat) et au niveau postdoctoral pour effectuer un stage de recherche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que toute th\u00e9matique scientifique puisse \u00eatre soutenue par le volet Recherche, conform\u00e9ment \u00e0 la d\u00e9claration conjointe sign\u00e9e le 6 mars 2015, les propositions ciblant les th\u00e9matiques suivantes, d\u00e9coulant de la 20<sup>e<\/sup>&nbsp;rencontre altern\u00e9e des premiers ministres (RAPM, 2018), seront prioritairement financ\u00e9es :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Strat\u00e9gie maritime;<\/li><li>D\u00e9veloppement nordique;<\/li><li>Innovation, cr\u00e9ativit\u00e9 et entrepreneuriat;<\/li><li>Num\u00e9rique et son appropriation dans les diverses sph\u00e8res de la soci\u00e9t\u00e9;<\/li><li>Intelligence artificielle;<\/li><li>Environnement, d\u00e9veloppement durable et lutte aux changements climatiques;<\/li><li>Changements d\u00e9mographiques et vieillissement de la population;<\/li><li>Innovation sociale;<\/li><li>\u00c9galit\u00e9 femme-homme.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Il revient \u00e0 la porteuse ou au porteur de justifier dans sa demande comment le projet s\u2019inscrit dans une ou des th\u00e9matiques prioritaires cibl\u00e9es, le cas \u00e9ch\u00e9ant.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Volet Formation<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ce volet vise \u00e0 am\u00e9liorer la formation universitaire \u00e0 tous les cycles d\u2019\u00e9tudes, y compris la formation continue en :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Encourageant les innovations p\u00e9dagogiques et la mise en place de programmes communs de formation;<\/li><li>Poursuivant le d\u00e9veloppement de la formation \u00e0 distance;<\/li><li>Soutenant le d\u00e9veloppement et l\u2019\u00e9volution de la p\u00e9dagogie universitaire.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Caract\u00e9ristiques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La subvention maximale accord\u00e9e \u00e0 chaque projet est de 30 000 $ pour la partie qu\u00e9b\u00e9coise et 20 000 \u20ac pour la partie fran\u00e7aise pour deux ans, au total. Les versements aux \u00e9tablissements seront d\u2019un maximum de 15 000 $ annuellement (FRQNT) et de 20 000\u20ac en un seul versement. La subvention n\u2019est pas renouvelable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aucuns frais indirects de la recherche (FIR) ne sont vers\u00e9s \u00e0 l\u2019\u00e9tablissement dans le cadre de ce Programme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Admissibilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les chercheuses et chercheurs, les \u00e9tablissements et les projets doivent respecter les conditions d\u2019admissibilit\u00e9 en vigueur dans les r\u00e8gles du programme ainsi que les RGC au moment de la pr\u00e9sentation de la demande de financement et pendant toute la p\u00e9riode d\u2019octroi couverte par la subvention. La non-admissibilit\u00e9 d\u2019une demande pr\u00e9sent\u00e9e par l\u2019une des parties, qu\u00e9b\u00e9coise ou fran\u00e7aise, entrainera la non-admissibilit\u00e9 de l\u2019autre.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Projet<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet doit \u00eatre sous la responsabilit\u00e9 de deux porteurs, l\u2019un d\u00e9sign\u00e9 par la partie qu\u00e9b\u00e9coise et l\u2019autre par la partie fran\u00e7aise. Les projets propos\u00e9s peuvent s\u2019inscrire dans tout secteur de recherche (sant\u00e9, sciences humaines et sociales, arts et lettres, sciences naturelles et g\u00e9nie) ou tout domaine de formation en enseignement sup\u00e9rieur.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Porteurs et porteuses<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la date limite de d\u00e9p\u00f4t des demandes et tel que pr\u00e9cis\u00e9 dans les RGC des FRQ, la porteuse ou le porteur de la partie qu\u00e9b\u00e9coise doit avoir le statut 1 de chercheuse ou chercheur universitaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La porteuse ou le porteur de la partie fran\u00e7aise du projet doit occuper un poste r\u00e9gulier (statutaire ou contrat de travail \u00e0 dur\u00e9e ind\u00e9termin\u00e9e (CDI)) dans un \u00e9tablissement d\u2019enseignement sup\u00e9rieur ou dans un organisme de recherche fran\u00e7ais, \u00e0 la date limite de d\u00e9p\u00f4t des demandes.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u00c9quipe<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe doit \u00eatre constitu\u00e9e d\u2019au moins deux chercheuses ou chercheurs pour la partie qu\u00e9b\u00e9coise et d\u2019au moins deux chercheuses ou chercheurs pour la partie fran\u00e7aise, incluant les deux porteurs de la demande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9quipe du projet peut \u00e9galement comprendre des personnes associ\u00e9es \u00e0 la recherche autres que des chercheuses ou chercheurs (personnel professionnel de recherche, professeures ou professeurs associ\u00e9s, etc.).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conditions additionnelles pour le volet Recherche seulement<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Le partenariat doit int\u00e9grer des \u00e9tudiantes ou \u00e9tudiants des cycles sup\u00e9rieurs et\/ou des postdoctorants et postdoctorantes.<\/li><li><strong>Les porteurs des deux parties doivent occuper un poste r\u00e9gulier, \u00e0 temps plein ou sous-octroi au sens du statut 1 des RGC, \u00e0 la date de d\u00e9p\u00f4t de la demande, et avoir soutenu leur th\u00e8se de doctorat apr\u00e8s le 1er janvier 2007 inclusivement.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Une chercheuse ou un chercheur qui aurait interrompu ou retard\u00e9 sa carri\u00e8re en raison de cong\u00e9s parentaux, d\u2019obligations familiales majeures, de situation de handicap ou pour des raisons de sant\u00e9 peut voir sa p\u00e9riode d\u2019admissibilit\u00e9 prolong\u00e9e. Les documents justificatifs doivent \u00eatre transmis avec la demande. Le FQRNT d\u00e9termine la prolongation \u00e0 accorder et peut demander des pi\u00e8ces justificatives compl\u00e9mentaires.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Restrictions<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Les chercheuses et chercheurs peuvent faire partie, au maximum, de deux demandes d\u00e9pos\u00e9es \u00e0 un m\u00eame concours ou financ\u00e9es dans la m\u00eame ann\u00e9e financi\u00e8re, dont maximum une seule \u00e0 titre de porteuse ou porteur. Ces deux demandes doivent \u00eatre pr\u00e9sent\u00e9es avec des \u00e9quipes diff\u00e9rentes et pour des projets diff\u00e9rents. Par exemple, une personne agissant \u00e0 titre de porteuse ou porteur d\u2019une demande financ\u00e9e en 2022-2023, qui recevra sa deuxi\u00e8me ann\u00e9e de financement en 2023-2024, peut d\u00e9poser au pr\u00e9sent concours, une seule demande et seulement \u00e0 titre de chercheuse ou chercheur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une demande de financement pour un m\u00eame projet ne peut \u00eatre soumise que par une seule \u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une demande de financement doit \u00eatre unique et ne pas avoir \u00e9t\u00e9 d\u00e9j\u00e0 financ\u00e9 dans le cadre des concours ant\u00e9rieurs de ce programme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le financement demand\u00e9 au Programme pour le projet ne doit pas exc\u00e9der deux ans et le budget doit respecter les bar\u00e8mes indiqu\u00e9s \u00e0 la section 7.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Demande<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e9ments absents du dossier ne seront pas demand\u00e9s \u00e0 la personne candidate. Toutes les pi\u00e8ces re\u00e7ues apr\u00e8s la date et heure limites de transmission des demandes au Fonds ne seront pas consid\u00e9r\u00e9es et il n\u2019y aura pas de mise \u00e0 jour des dossiers. Toute page exc\u00e9dentaire sera retir\u00e9e du dossier. Ces r\u00e8gles seront strictement appliqu\u00e9es. Toute demande incompl\u00e8te rend la demande non-admissible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les documents joints et sections du formulaire \u00e9lectronique, incluant les contributions d\u00e9taill\u00e9es du CV doivent satisfaire aux exigences pr\u00e9sent\u00e9es dans les documents Instructions pour les contributions d\u00e9taill\u00e9es et le CV commun canadien \u2013 FRQNT et FRQ \u2013 Normes de pr\u00e9sentation des fichiers joints (PDF) aux formulaires FRQnet disponibles dans la section Documents du Portfolio \u00e9lectronique FRQnet. Le non-respect de ces exigences pourra entrainer la NON-ADMISSIBILIT\u00c9 de la demande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une mise \u00e0 jour du profil tenant compte du formulaire d\u2019auto-identification de la porteuse ou du porteur qu\u00e9b\u00e9cois et fran\u00e7ais ainsi que toutes les cochercheuses et cochercheurs qu\u00e9b\u00e9cois devra \u00eatre compl\u00e9t\u00e9 via le Portfolio \u00e9lectronique FRQnet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demande comprend les documents suivants :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Formulaire de demande de financement (Portfolio \u00e9lectronique FRQnet)<\/strong>&nbsp;inclut les onglets suivants:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Cochercheurs ou cochercheuses : Joindre le fichier Composition de l\u2019\u00e9quipe-France pour la partie fran\u00e7aise;<\/li><li>Description du projet : description en lien avec les crit\u00e8res d\u2019\u00e9valuation de&nbsp;<strong>9 pages<\/strong>&nbsp;qui explique en d\u00e9tail (Voir section 6): la pertinence du projet en lien avec les th\u00e9matiques (1 page), l\u2019atteinte des objectifs \u00e9num\u00e9r\u00e9s du programme \u00e0 la section 1 (1 page), la description du projet (4 pages), l\u2019\u00e9ch\u00e9ancier (2 pages) ainsi que les collaborations et perspectives futures (1 page).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette demande est r\u00e9dig\u00e9e conjointement par les deux parties et d\u00e9pos\u00e9e par la porteuse ou le porteur de la partie qu\u00e9b\u00e9coise.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Budget :<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A. Joindre le fichier format FRQNT du Budget-France de la partie fran\u00e7aise;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B. Joindre le fichier Justification du montant demand\u00e9 de la partie Qu\u00e9b\u00e9coise (1 page).<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Autres documents :<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A. Joindre le fichier du CV pour la porteuse ou le porteur de la partie fran\u00e7aise dans le format pr\u00e9cis\u00e9 ci-dessous;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B. Joindre le fichier Engagement de la porteuse ou du porteur de la partie fran\u00e7aise d\u00fbment sign\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Signature et transmission.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Curriculum vitae<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les curriculums vitae des porteuses et porteurs qu\u00e9b\u00e9cois et fran\u00e7ais doivent \u00eatre joints au dossier. Les autres membres de l\u2019\u00e9quipe n\u2019ont pas \u00e0 fournir de CV.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Pour la porteuse ou le porteur de la partie qu\u00e9b\u00e9coise,&nbsp;<strong>le CV commun canadien<\/strong>&nbsp;mis \u00e0 jour (version FRQS, FRQNT ou FRQSC) incluant le fichier PDF des Contributions d\u00e9taill\u00e9es, est exig\u00e9.<\/li><li>Pour la porteuse ou le porteur de la partie fran\u00e7aise, un CV en format libre est permis. Ce CV doit obligatoirement :<ul><li>Indiquer le jour, le mois et l\u2019ann\u00e9e de la soutenance de th\u00e8se de doctorat;<\/li><li>Indiquer l\u2019adresse postale professionnelle;<\/li><li>\u00catre d\u2019un maximum de 20 pages.<\/li><\/ul><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ensemble des documents \u00e0 joindre dans le format demand\u00e9 sont disponibles en format PDF dans la section \u00ab Bo\u00eete \u00e0 outils \u00bb. Aucun autre format ne sera accept\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IMPORTANT<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toute demande recevable mais incompl\u00e8te (c\u2019est-\u00e0-dire ne pr\u00e9sentant pas l\u2019ensemble des documents mentionn\u00e9s ci-dessus dans le format demand\u00e9) ou ne r\u00e9pondant pas aux conditions d\u2019admissibilit\u00e9 sera consid\u00e9r\u00e9 NON-ADMISSIBLE.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9valuation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les demandes qui respectent les conditions d\u2019admissibilit\u00e9 font l\u2019objet d\u2019une \u00e9valuation scientifique r\u00e9alis\u00e9e par le Minist\u00e8re de l\u02bcEnseignement Sup\u00e9rieur et de la Recherche (MESR) et le FRQNT. Cette \u00e9valuation r\u00e9unit des expertes et experts issus de domaines pertinents aux demandes. Le r\u00e9sultat de cette \u00e9valuation et le classement des demandes sont remis aux membres du CFQCU qui d\u00e9cident ultimement du financement des projets.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Crit\u00e8res d\u2019\u00e9valuation pour le volet \u00ab Recherche \u00bb<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet est \u00e9valu\u00e9 sur la base des crit\u00e8res scientifiques suivants :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La qualit\u00e9 du projet (30 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualit\u00e9 scientifique du projet;<\/li><li>Structures d\u2019accueil et d\u2019encadrement \u00e0 l\u2019intention d\u2019\u00e9tudiantes et d\u2019\u00e9tudiants des 2e et 3e cycles et\/ou des postdoctorants et postdoctorantes;<\/li><li>Articulation formation-recherche;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les retomb\u00e9es du projet (30 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Caract\u00e8res novateur et structurant (\u00e9mergence d\u2019une fili\u00e8re d\u2019excellence franco-qu\u00e9b\u00e9coise);<\/li><li>Diffusion et visibilit\u00e9;<\/li><li>Transfert de connaissances et d\u2019expertises vers les milieux socio-\u00e9conomiques et culturels;<\/li><li>Effet structurant pour positionner l\u2019expertise en France et au Qu\u00e9bec;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019\u00e9quipe (25 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualit\u00e9 et ad\u00e9quation des profils des chercheuses et chercheurs;<\/li><li>\u00c9mergence et compl\u00e9mentarit\u00e9 du partenariat autour du th\u00e8me retenu;<\/li><li>Participation et mobilit\u00e9 d\u2019\u00e9tudiantes ou \u00e9tudiants ou de stagiaires de recherche postdoctorale au projet (r\u00f4les, contributions);<\/li><li>Prise en compte des principes d\u2019\u00e9quit\u00e9, diversit\u00e9 et inclusion<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019organisation et la gestion (15 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualit\u00e9 de la planification du projet et pertinence des d\u00e9placements propos\u00e9s pour l\u2019avancement du projet;<\/li><li>Utilisation maximale des services et ressources disponibles dans les \u00e9tablissements;<\/li><li>Pr\u00e9visions budg\u00e9taires selon les d\u00e9penses admissibles (voir la section 7.2 \u00ab Bar\u00e8mes financiers \u00bb);<\/li><li>Financement demand\u00e9 (et confirm\u00e9, le cas \u00e9ch\u00e9ant) \u00e0 des sources ext\u00e9rieures au CFQCU;<\/li><li>Poursuite du programme de recherche au terme du financement.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Crit\u00e8res d\u2019\u00e9valuation pour le volet \u00ab Formation \u00bb<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet est \u00e9valu\u00e9 sur la base des crit\u00e8res scientifiques suivants :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La qualit\u00e9 du projet (30 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualit\u00e9 p\u00e9dagogique du projet;<\/li><li>Pr\u00e9sence d\u2019un ensemble de strat\u00e9gies et d\u2019approches permettant au projet d\u2019\u00eatre une source de nouveaux savoirs et d\u2019innovation, principalement dans l\u2019utilisation p\u00e9dagogique du num\u00e9rique;<\/li><li>Prise en compte de l\u2019offre d\u2019activit\u00e9s similaires dans le domaine de formation;<\/li><li>Liens du projet avec les orientations strat\u00e9giques et les priorit\u00e9s de d\u00e9veloppement des institutions;<\/li><li>Enrichissement des objectifs du projet par la collaboration entre les partenaires;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les retomb\u00e9es du projet (30 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Impacts et r\u00e9sultats anticip\u00e9s sur l\u2019enseignement ou l\u2019apprentissage (impacts sur les pratiques p\u00e9dagogiques, l\u2019exp\u00e9rience d\u2019apprentissage, les enseignants ou les apprenants);<\/li><li>R\u00e9alisme et clart\u00e9 de la strat\u00e9gie permettant d\u2019assurer la p\u00e9rennit\u00e9 et la transf\u00e9rabilit\u00e9 du projet;<\/li><li>Potentiel du projet comme \u00e9l\u00e9ment de distinction dans le r\u00e9seau universitaire francophone;<\/li><li>Cr\u00e9ation de programmes de formation conjoints;<\/li><li>Diffusion et visibilit\u00e9;<\/li><li>Participation et mobilit\u00e9 d\u2019\u00e9tudiantes et d\u2019\u00e9tudiants et\/ou de stagiaires de recherche postdoctorale impliqu\u00e9s dans le projet (r\u00f4les, contributions);<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019\u00e9quipe (25 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>R\u00e9alisation d\u2019initiatives ou d\u2019activit\u00e9s particuli\u00e8res d\u00e9montrant l\u2019engagement et le leadership en p\u00e9dagogie dans le domaine de formation;<\/li><li>Compl\u00e9mentarit\u00e9 et synergie entre les chercheuses et chercheurs;<\/li><li>R\u00e9partition \u00e9quilibr\u00e9e entre les partenaires fran\u00e7ais et qu\u00e9b\u00e9cois;<\/li><li>Nature et mode de gestion du partenariat;<\/li><li>Prise en compte des principes d\u2019\u00e9quit\u00e9, diversit\u00e9 et inclusion<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019organisation et la gestion (15 points)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualit\u00e9 de la planification du projet et pertinence des d\u00e9placements propos\u00e9s pour l\u2019avancement du projet;<\/li><li>Utilisation maximale des services et ressources disponibles dans les \u00e9tablissements;<\/li><li>Pr\u00e9visions budg\u00e9taires selon les d\u00e9penses admissibles (voir la section 7.1);<\/li><li>Financement demand\u00e9 (et confirm\u00e9, le cas \u00e9ch\u00e9ant) \u00e0 des sources ext\u00e9rieures au CFQCU.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">6.3 Attribution des subventions<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Les subventions \u00ab Recherche \u00bb et \u00ab Formation \u00bb seront attribu\u00e9es par le CFQCU en tenant compte de l\u2019ensemble des \u00e9l\u00e9ments suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u2019\u00e9valuation scientifique (sections 6.1 et 6.2) ;<\/li><li>Les objectifs du programme (section 1) ;<\/li><li>La pr\u00e9sence de demandes d\u00e9pos\u00e9es par des \u00e9tablissements admissibles en r\u00e9gion ; et<\/li><li>L\u2019accord avec les th\u00e9matiques scientifiques Franco \u2013 Qu\u00e9b\u00e9coises prioritaires.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>L\u2019\u00e9valuation de la demande de financement est assortie&nbsp;<strong>d\u2019un seuil de passage de la cote A.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IMPORTANT POUR LA PARTIE FRAN\u00c7AISE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les projets soumis \u00e0 cet appel \u00e0 projets peuvent faire l\u2019objet d\u2019un examen au titre de la PPST (Protection du potentiel scientifique et technique et intelligence \u00e9conomique). Pour plus d\u2019information sur ce dispositif&nbsp;<a href=\"https:\/\/www.enseignementsup-recherche.gouv.fr\/fr\/protection-du-potentiel-scientifique-et-technique-et-intelligence-economique-ppst-46370\">https:\/\/www.enseignementsup-recherche.gouv.fr\/fr\/protection-du-potentiel-scientifique-et-technique-et-intelligence-economique-ppst-46370<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9penses<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00e9penses admissibles<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes les d\u00e9penses pr\u00e9vues doivent avoir un lien direct avec le projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que ce soit pour :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les chercheuses et les chercheurs de la partie qu\u00e9b\u00e9coise, leurs \u00e9tudiantes et \u00e9tudiants de ma\u00eetrise\/master et de doctorat, et leurs postdoctorantes et postdoctorants qui se d\u00e9placent en France;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ou pour<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les chercheuses et les chercheurs de la partie fran\u00e7aise, leurs \u00e9tudiantes et \u00e9tudiants de ma\u00eetrise\/master et de doctorat, et leurs postdoctorantes et postdoctorants qui se d\u00e9placent au Qu\u00e9bec;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Seules les d\u00e9penses ci-dessous sont admissibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Frais de d\u00e9placement<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Vols internationaux aller-retour en classe \u00e9conomique, entre le Qu\u00e9bec et la France dans le respect du bar\u00e8me financier indiqu\u00e9 ci-dessous;<\/li><li>Frais pour les pr\u00e9acheminements et post acheminements au Qu\u00e9bec ou en France (d\u00e9placements a\u00e9roport \u2013 port d\u2019attache).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Frais quotidiens de s\u00e9jour<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Dans le respect des bar\u00e8mes financiers indiqu\u00e9s ci-dessous. Ces frais incluent les d\u00e9penses de restauration et d\u2019h\u00e9bergement.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Frais pour la valorisation des r\u00e9sultats<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Publications d\u2019article, actes de colloque, etc.;<\/li><li>La participation \u00e0 des conf\u00e9rences ailleurs qu\u2019au Qu\u00e9bec ou en France est seulement admissible pour pr\u00e9senter des travaux d\u00e9coulant du projet propos\u00e9. Les d\u00e9penses admissibles pour ces d\u00e9placements doivent toutefois respecter les m\u00eames bar\u00e8mes que les d\u00e9placements entre le Qu\u00e9bec et la France.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Bar\u00e8mes financiers<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le respect de ces bar\u00e8mes financiers est obligatoire. Le d\u00e9faut de respecter ces bar\u00e8mes est susceptible de r\u00e9duire le montant de la subvention octroy\u00e9e au projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consultez les bar\u00e8mes financiers ici : <a href=\"https:\/\/frq.gouv.qc.ca\/programme\/programme-samuel-de-champlain-2023-2024\/#depenses\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/frq.gouv.qc.ca\/programme\/programme-samuel-de-champlain-2023-2024\/#depenses <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Participantes et participants de nationalit\u00e9 \u00e9trang\u00e8re<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si un participant est de nationalit\u00e9 autre que canadienne ou fran\u00e7aise, un visa peut lui \u00eatre demand\u00e9 pour entrer au Canada. Veuillez consulter le site de l\u2019Ambassade du Canada (<a href=\"http:\/\/www.france.gc.ca\/\">www.france.gc.ca<\/a>) pour conna\u00eetre la liste des pays dont les ressortissants doivent poss\u00e9der un visa pour entrer au Canada et la proc\u00e9dure pour en obtenir un. Veuillez \u00e9galement consid\u00e9rer un d\u00e9lai suppl\u00e9mentaire pour faire la demande de visa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00e9penses non admissibles (pour la partie qu\u00e9b\u00e9coise et la partie fran\u00e7aise)<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter que, pour les deux parties, les d\u00e9penses suivantes ne sont pas admissibles :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les d\u00e9penses de salaires;<\/li><li>Les frais de d\u00e9placement et les frais quotidien pour le s\u00e9jour de membres du personnel de recherche autre que les chercheuses et chercheurs, les \u00e9tudiantes et \u00e9tudiants de ma\u00eetrise\/master et de doctorat et les postdoctorantes et postdoctorants au projet;<\/li><li>Frais de bagages exc\u00e9dentaires (ne s\u2019applique pas au mat\u00e9riel n\u00e9cessaire pour le projet);<\/li><li>Frais de d\u00e9placement et allocation forfaitaire quotidienne pour des s\u00e9jours sur un territoire situ\u00e9 \u00e0 l\u2019ext\u00e9rieur de la France et du Qu\u00e9bec, sauf si ce territoire constitue un lieu de collaboration franco-qu\u00e9b\u00e9cois sp\u00e9cifique. Dans ce cas, ce choix doit \u00eatre clairement justifi\u00e9 par le projet de recherche ou de formation associ\u00e9 au programme;<\/li><li>Cumul, pour une m\u00eame personne, d\u2019un s\u00e9jour d\u2019apprentissage et d\u2019une mission lors d\u2019un m\u00eame s\u00e9jour;<\/li><li>Compl\u00e9ments de bourse;<\/li><li>Les frais de gestion.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Gestion et suivi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La subvention est accord\u00e9e pour une p\u00e9riode approximative de deux ans. Veuillez noter qu\u2019au Qu\u00e9bec les exercices financiers sont du&nbsp;<strong>1<sup>er<\/sup>&nbsp;avril au 31 mars<\/strong>&nbsp;et en France ils sont du&nbsp;<strong>1<sup>er<\/sup>&nbsp;janvier au 31 d\u00e9cembre<\/strong>&nbsp;expliquant ainsi cette approximation. Pour la partie qu\u00e9b\u00e9coise, la subvention couvre les exercices financiers 2023-2024 et 2024-2025. Pour la partie fran\u00e7aise, la subvention couvre les exercices financiers 2023 et 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toute modification importante au projet, par la partie qu\u00e9b\u00e9coise et\/ou par la partie fran\u00e7aise, apport\u00e9e en cours d\u2019octroi par rapport au projet initialement d\u00e9crit dans la demande doit \u00eatre approuv\u00e9e. La porteuse ou le porteur de la partie qu\u00e9b\u00e9coise doit indiquer cette modification dans le Portfolio \u00e9lectronique FRQnet et en fournir la justification. Puis, l\u2019une ou l\u2019autre des parties ou les deux doivent envoyer un courriel comportant ces informations au FRQNT et au CGF. Se r\u00e9f\u00e9rer \u00e0 l\u2019article.6.5 des RGC pour plus de pr\u00e9cisions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un report des sommes non d\u00e9pens\u00e9es au terme des travaux et les trop-per\u00e7us pour une 3e ann\u00e9e suppl\u00e9mentaire est conditionnel \u00e0 l\u2019approbation du FRQNT et du CGF. Une demande de report de l\u2019une ou l\u2019autre des parties doit \u00eatre adress\u00e9e au FRQNT, lequel prendra une d\u00e9cision concert\u00e9e avec le CGF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au terme du financement, les porteuses et porteurs des projets soutenus par le CFQCU s\u2019engagent \u00e0 fournir un bref rapport final d\u2019activit\u00e9s selon le format pr\u00e9sent\u00e9 dans le document \u00ab&nbsp;Rapport final \u00bb disponible dans la section \u00ab&nbsp;Bo\u00eete \u00e0 outils&nbsp;\u00bb. Toute demande de report de remise du rapport doit \u00eatre adress\u00e9e au FRQNT qui autorisera, en concertation avec le CGF, ce report pour les deux parties. Tout rapport final d\u00e9pos\u00e9 par l\u2019une des deux parties met fin au projet de l\u2019autre partie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les porteuses et porteurs des projets consentent \u00e0 ce que ce rapport, outre la partie financi\u00e8re, soit diffus\u00e9 \u00e0 la communaut\u00e9 universitaire via le site internet du CFQCU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La partie qu\u00e9b\u00e9coise du Programme est financ\u00e9e par le minist\u00e8re de l\u2019Enseignement sup\u00e9rieur (MES) et le minist\u00e8re des Relations internationales et de la Francophonie (MRIF). Le suivi du financement de la partie qu\u00e9b\u00e9coise est confi\u00e9 au FRQNT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La partie fran\u00e7aise du Programme est financ\u00e9e par le minist\u00e8re de l\u02bcEnseignement Sup\u00e9rieur et de la Recherche (MESR) et par le minist\u00e8re de l\u2019Europe et des Affaires \u00c9trang\u00e8res (MEAE). Le suivi du financement de la partie fran\u00e7aise est confi\u00e9 au CGF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le suivi du financement des projets par le FRQNT et par le CGF est concert\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Diffusion en libre acc\u00e8s<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les publications examin\u00e9es par les pairs qui d\u00e9couleront des travaux de recherche rendus possibles par cet octroi devront \u00eatre diffus\u00e9es en libre acc\u00e8s imm\u00e9diat (sans embargo), sous licence ouverte, conform\u00e9ment \u00e0 la&nbsp;<em>Politique de diffusion en libre acc\u00e8s<\/em>&nbsp;(r\u00e9vis\u00e9e en 2022).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prise d&#8217;effet<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la partie qu\u00e9b\u00e9coise, les pr\u00e9sentes r\u00e8gles s\u2019appliquent \u00e0 l\u2019exercice financier&nbsp;2023-2024. Pour la partie fran\u00e7aise, ces r\u00e8gles s\u2019appliquent \u00e0 l\u2019exercice financier 2023.<\/p>","protected":false},"author":118,"featured_media":1217,"template":"","coauthors":[253,232],"class_list":["post-4002","appel-a-projets","type-appel-a-projets","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/ty\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"D\u00e9sol\u00e9, ce contenu est uniquement disponible en Fran\u00e7ais. Ce programme est lanc\u00e9 par les Fonds de Recherche du Qu\u00e9bec (FRQ) et s\u2019adresse aux enseignants-chercheurs de toutes les disciplines. Objectifs Le Programme a pour objectif de contribuer \u00e0 l\u2019excellence de la coop\u00e9ration universitaire et scientifique franco-qu\u00e9b\u00e9coise, \u00e0 son d\u00e9veloppement et \u00e0 sa diffusion.&nbsp;Une attention particuli\u00e8re sera&hellip; Continue reading FRQ &#8211; Programme Samuel-De-Champlain 2023-2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-10T20:59:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/07\/egwhibec0ck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"presta, Virginia Godefroy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/\",\"name\":\"FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/egwhibec0ck.jpg\",\"datePublished\":\"2022-08-10T20:50:50+00:00\",\"dateModified\":\"2022-08-10T20:59:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/#breadcrumb\"},\"inLanguage\":\"ty\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ty\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/egwhibec0ck.jpg\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/egwhibec0ck.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"white and brown printed paper\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/appel-a-projets\\\/aap-samuel-de-champlain-2022-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRQ &#8211; Programme Samuel-De-Champlain 2023-2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ty\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ty\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/ty\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/","og_locale":"en_US","og_type":"article","og_title":"FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF","og_description":"D\u00e9sol\u00e9, ce contenu est uniquement disponible en Fran\u00e7ais. Ce programme est lanc\u00e9 par les Fonds de Recherche du Qu\u00e9bec (FRQ) et s\u2019adresse aux enseignants-chercheurs de toutes les disciplines. Objectifs Le Programme a pour objectif de contribuer \u00e0 l\u2019excellence de la coop\u00e9ration universitaire et scientifique franco-qu\u00e9b\u00e9coise, \u00e0 son d\u00e9veloppement et \u00e0 sa diffusion.&nbsp;Une attention particuli\u00e8re sera&hellip; Continue reading FRQ &#8211; Programme Samuel-De-Champlain 2023-2024","og_url":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2022-08-10T20:59:37+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/07\/egwhibec0ck.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Est. reading time":"18 minutes","Written by":"presta, Virginia Godefroy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/","url":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/","name":"FRQ - Programme Samuel-De-Champlain 2023-2024 &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/07\/egwhibec0ck.jpg","datePublished":"2022-08-10T20:50:50+00:00","dateModified":"2022-08-10T20:59:37+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/#breadcrumb"},"inLanguage":"ty","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/"]}]},{"@type":"ImageObject","inLanguage":"ty","@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/07\/egwhibec0ck.jpg","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/07\/egwhibec0ck.jpg","width":1600,"height":1200,"caption":"white and brown printed paper"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/fr\/appel-a-projets\/aap-samuel-de-champlain-2022-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"FRQ &#8211; Programme Samuel-De-Champlain 2023-2024"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ty"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"ty","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/appel-a-projets\/4002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/appel-a-projets"}],"about":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/types\/appel-a-projets"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":6,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/appel-a-projets\/4002\/revisions"}],"predecessor-version":[{"id":4016,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/appel-a-projets\/4002\/revisions\/4016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/media\/1217"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/media?parent=4002"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/coauthors?post=4002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}