{"id":7398,"date":"2023-11-03T15:44:52","date_gmt":"2023-11-04T01:44:52","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=actualite&#038;p=7398"},"modified":"2023-11-03T15:44:55","modified_gmt":"2023-11-04T01:44:55","slug":"perliculture-durable-la-polynesie-a-la-pointe-de-linnovation","status":"publish","type":"actualite","link":"https:\/\/recherche.upf.pf\/ty\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/","title":{"rendered":"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation !"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ty\">D\u00e9sol\u00e9, ce contenu est uniquement disponible en <a href=\"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/actualite\/7398\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p><p class=\"wp-block-paragraph\">L&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise, en \u00e9troite collaboration avec la soci\u00e9t\u00e9 PLASTISERD, l&#8217;IRD, la DRM et leur partenaire n\u00e9oz\u00e9landais SCION, d\u00e9voile une avanc\u00e9e majeure dans le domaine de la perliculture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la premi\u00e8re fois \u00e0 l&#8217;\u00e9chelle mondiale, un collecteur de naissains de bivalves biod\u00e9gradable a \u00e9t\u00e9 d\u00e9ploy\u00e9 dans un atoll perlicole des Tuamotu en partenariat avec un perliculteur. Ces dispositifs de collecte, dont l&#8217;efficacit\u00e9 a \u00e9t\u00e9 prouv\u00e9e avec une version pr\u00e9c\u00e9dente, ont \u00e9t\u00e9 fabriqu\u00e9s localement dans le cadre du projet BioPLATES. Ce projet est l&#8217;un des dix projets d&#8217;innovation \u00e0 fort impact accompagn\u00e9s par le dispositif Polynnov dans le cadre du projet N\u0101hiti. Cette innovation, fruit d&#8217;une synergie entre recherche acad\u00e9mique, expertise industrielle et soutien institutionnel, fait l&#8217;objet d&#8217;un brevet europ\u00e9en. Transposable \u00e0 l&#8217;international, elle permettra de tendre vers une perliculture durable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un grand merci \u00e0 l&#8217;\u00e9quipe de l&#8217;@UPF et \u00e0 tous ses partenaires pour cette contribution majeure \u00e0 la perliculture mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.tntv.pf\/tntvnews\/polynesie\/environnement\/perliculture-lupf-realise-une-premiere-mondiale-en-concevant-un-collecteur-biodegradable\/\">Cliquez ici pour acc\u00e9der \u00e0 l&#8217;article<\/a><\/p>","protected":false},"author":101,"featured_media":0,"template":"","coauthors":[227],"class_list":["post-7398","actualite","type-actualite","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/ty\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"D\u00e9sol\u00e9, ce contenu est uniquement disponible en Fran\u00e7ais. L&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise, en \u00e9troite collaboration avec la soci\u00e9t\u00e9 PLASTISERD, l&#8217;IRD, la DRM et leur partenaire n\u00e9oz\u00e9landais SCION, d\u00e9voile une avanc\u00e9e majeure dans le domaine de la perliculture. Pour la premi\u00e8re fois \u00e0 l&#8217;\u00e9chelle mondiale, un collecteur de naissains de bivalves biod\u00e9gradable a \u00e9t\u00e9 d\u00e9ploy\u00e9&hellip; Continue reading Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-04T01:44:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Melanie Bontant\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\\\/\",\"name\":\"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"datePublished\":\"2023-11-04T01:44:52+00:00\",\"dateModified\":\"2023-11-04T01:44:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\\\/#breadcrumb\"},\"inLanguage\":\"ty\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ty\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ty\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/ty\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/","og_locale":"en_US","og_type":"article","og_title":"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF","og_description":"D\u00e9sol\u00e9, ce contenu est uniquement disponible en Fran\u00e7ais. L&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise, en \u00e9troite collaboration avec la soci\u00e9t\u00e9 PLASTISERD, l&#8217;IRD, la DRM et leur partenaire n\u00e9oz\u00e9landais SCION, d\u00e9voile une avanc\u00e9e majeure dans le domaine de la perliculture. Pour la premi\u00e8re fois \u00e0 l&#8217;\u00e9chelle mondiale, un collecteur de naissains de bivalves biod\u00e9gradable a \u00e9t\u00e9 d\u00e9ploy\u00e9&hellip; Continue reading Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation !","og_url":"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2023-11-04T01:44:55+00:00","twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Est. reading time":"1 minute","Written by":"Melanie Bontant"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/","url":"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/","name":"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation ! &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"datePublished":"2023-11-04T01:44:52+00:00","dateModified":"2023-11-04T01:44:55+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/#breadcrumb"},"inLanguage":"ty","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/actualite\/perliculture-durable-la-polynesie-a-la-pointe-de-linnovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Perliculture durable : la Polyn\u00e9sie \u00e0 la pointe de l\u2019innovation !"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ty"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"ty","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/actualite\/7398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/actualite"}],"about":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/types\/actualite"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/users\/101"}],"version-history":[{"count":5,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/actualite\/7398\/revisions"}],"predecessor-version":[{"id":7411,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/actualite\/7398\/revisions\/7411"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/media?parent=7398"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/ty\/wp-json\/wp\/v2\/coauthors?post=7398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}