{"id":3613,"date":"2022-07-12T13:43:18","date_gmt":"2022-07-12T23:43:18","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=projet&#038;p=3613"},"modified":"2022-07-12T13:51:51","modified_gmt":"2022-07-12T23:51:51","slug":"projet-protege","status":"publish","type":"projet","link":"https:\/\/recherche.upf.pf\/fr\/projet\/projet-protege\/","title":{"rendered":"PROTEGE"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet porte sur \u00ab l\u2019\u00e9laboration et la diffusion d\u2019un protocole de coloration des feuilles de pandanus (<em>Pandanus tectorius<\/em>) \u00e0 partir des plantes tinctoriales polyn\u00e9siennes \u00bb. La biodiversit\u00e9 de la Polyn\u00e9sie fran\u00e7aise propose une palette de pigments v\u00e9g\u00e9taux li\u00e9e \u00e0 l\u2019utilisation traditionnelle et dont certains ne sont pas encore exploit\u00e9s pour la production de rouleaux de pandanus. Les objectifs sont de pr\u00e9server et d\u2019am\u00e9liorer le savoir-faire local sur la pr\u00e9paration et la conservation des feuilles de pandanus ainsi que de proposer de nouveaux colorants naturels (couleurs jaune, verte, marron, rouge, blanche et noire).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les travaux de recherche s\u2019articuleront principalement autour de trois approches :&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Une <strong>approche botanique <\/strong>(Volet 1) pour s\u00e9lectionner des plantes tinctoriales pr\u00e9sentes parmi la biodiversit\u00e9 de la Polyn\u00e9sie fran\u00e7aise.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Une <strong>approche phytochimique et biologique <\/strong>(Volet 2) pour approfondir les connaissances scientifiques des plantes cibl\u00e9es en d\u00e9veloppant une m\u00e9thode d\u2019extraction et de caract\u00e9risation des pigments v\u00e9g\u00e9taux : analyse chromatographique, pouvoir colorant, stabilit\u00e9 (effet pH et temp\u00e9rature) et propri\u00e9t\u00e9s antioxydantes (pouvoir anti radicalaire) et antimicrobiennes des pigments.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Une <strong>approche de transmission de connaissances <\/strong>(Volet 3) en \u00e9tablissant des protocoles, restituant oralement et avec des fiches techniques les am\u00e9liorations ainsi qu\u2019en accompagnant les artisans des Australes dans le processus de coloration des feuilles de pandanus.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par l\u2019interm\u00e9diaire de ces trois volets, il sera possible de fournir un\/des \u00ab protocoles \u00bb et\/ou \u00ab recettes \u00bb optimis\u00e9s (bonne stabilit\u00e9 des feuilles de pandanus s\u00e9ch\u00e9es pr\u00e9par\u00e9es \u00e0 moindre co\u00fbt) ainsi que de proposer des plantes alternatives et de nouvelles couleurs naturelles apportant ainsi des perspectives de valorisation. Ces nouvelles solutions ainsi que l\u2019utilisation de nouveaux colorants naturels (plantes tinctoriales) et de mordants naturels (substances permettant de fixer la couleur) ont pour but de valoriser les ressources locales par des m\u00e9thodes en faveur de l\u2019environnement ce qui conduit \u00e0 un d\u00e9veloppement durable de la fili\u00e8re pandanus.&nbsp;<\/p>","protected":false},"author":118,"featured_media":0,"template":"","coauthors":[253],"class_list":["post-3613","projet","type-projet","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROTEGE &#8226; Recherche UPF<\/title>\n<meta name=\"description\" content=\"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/fr\/projet\/projet-protege\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROTEGE &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/projet\/projet-protege\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T23:51:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"presta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/projet\\\/projet-protege\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/projet\\\/projet-protege\\\/\",\"name\":\"PROTEGE &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"datePublished\":\"2022-07-12T23:43:18+00:00\",\"dateModified\":\"2022-07-12T23:51:51+00:00\",\"description\":\"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/projet\\\/projet-protege\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/projet\\\/projet-protege\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/projet\\\/projet-protege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROTEGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROTEGE &#8226; Recherche UPF","description":"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/fr\/projet\/projet-protege\/","og_locale":"fr_FR","og_type":"article","og_title":"PROTEGE &#8226; Recherche UPF","og_description":"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.","og_url":"https:\/\/recherche.upf.pf\/projet\/projet-protege\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2022-07-12T23:51:51+00:00","twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes","Written by":"presta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/projet\/projet-protege\/","url":"https:\/\/recherche.upf.pf\/projet\/projet-protege\/","name":"PROTEGE &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"datePublished":"2022-07-12T23:43:18+00:00","dateModified":"2022-07-12T23:51:51+00:00","description":"Pour l\u2019\u00e9laboration et pour la diffusion d\u2019un protocole de coloration des feuilles de pandanus \u00e0 partir des plantes tinctoriales polyn\u00e9siennes.","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/projet\/projet-protege\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/projet\/projet-protege\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/projet\/projet-protege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"PROTEGE"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/projet\/3613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/projet"}],"about":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/types\/projet"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":5,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/projet\/3613\/revisions"}],"predecessor-version":[{"id":3626,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/projet\/3613\/revisions\/3626"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media?parent=3613"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/coauthors?post=3613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}