{"id":1202,"date":"2021-07-02T10:13:48","date_gmt":"2021-07-02T20:13:48","guid":{"rendered":"https:\/\/recherche.upf.pf\/?page_id=1202"},"modified":"2022-08-16T10:30:42","modified_gmt":"2022-08-16T20:30:42","slug":"statuts","status":"publish","type":"page","link":"https:\/\/recherche.upf.pf\/fr\/statuts\/","title":{"rendered":"Statuts"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La commission de la recherche participe \u00e0 l\u2019\u00e9laboration de la politique de recherche et de valorisation de l&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La composition et les missions de la commission recherche sont d\u00e9finis par les statuts de l&#8217;universit\u00e9 (titre 3, chapitre 3, article 24).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez consulter les statuts de l&#8217;UPF directement sur <a href=\"https:\/\/www.upf.pf\/fr\/rapports-supports-documents-telecharger\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.upf.pf\/fr\/rapports-supports-documents-telecharger<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En savoir + sur la <a href=\"https:\/\/recherche.upf.pf\/politique-de-recherche\/\">politique de recherche de l&#8217;UPF<\/a>.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>La commission de la recherche participe \u00e0 l\u2019\u00e9laboration de la politique de recherche et de valorisation de l&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise. La composition et les missions de la commission recherche sont d\u00e9finis par les statuts de l&#8217;universit\u00e9 (titre 3, chapitre 3, article 24). Vous pouvez consulter les statuts de l&#8217;UPF directement sur https:\/\/www.upf.pf\/fr\/rapports-supports-documents-telecharger. En&hellip; <a class=\"more-link\" href=\"https:\/\/recherche.upf.pf\/fr\/statuts\/\">Continue reading <span class=\"screen-reader-text\">Statuts<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"1","_relevanssi_noindex_reason":"","footnotes":""},"coauthors":[227],"class_list":["post-1202","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Statuts &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/fr\/statuts\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statuts &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"La commission de la recherche participe \u00e0 l\u2019\u00e9laboration de la politique de recherche et de valorisation de l&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise. La composition et les missions de la commission recherche sont d\u00e9finis par les statuts de l&#8217;universit\u00e9 (titre 3, chapitre 3, article 24). Vous pouvez consulter les statuts de l&#8217;UPF directement sur https:\/\/www.upf.pf\/fr\/rapports-supports-documents-telecharger. En&hellip; Continue reading Statuts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/statuts\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T20:30:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Melanie Bontant\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/statuts\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/statuts\\\/\",\"name\":\"Statuts &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"datePublished\":\"2021-07-02T20:13:48+00:00\",\"dateModified\":\"2022-08-16T20:30:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/statuts\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/statuts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/statuts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statuts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Statuts &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/fr\/statuts\/","og_locale":"fr_FR","og_type":"article","og_title":"Statuts &#8226; Recherche UPF","og_description":"La commission de la recherche participe \u00e0 l\u2019\u00e9laboration de la politique de recherche et de valorisation de l&#8217;Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise. La composition et les missions de la commission recherche sont d\u00e9finis par les statuts de l&#8217;universit\u00e9 (titre 3, chapitre 3, article 24). Vous pouvez consulter les statuts de l&#8217;UPF directement sur https:\/\/www.upf.pf\/fr\/rapports-supports-documents-telecharger. En&hellip; Continue reading Statuts","og_url":"https:\/\/recherche.upf.pf\/statuts\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2022-08-16T20:30:42+00:00","twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Written by":"Melanie Bontant"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/statuts\/","url":"https:\/\/recherche.upf.pf\/statuts\/","name":"Statuts &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"datePublished":"2021-07-02T20:13:48+00:00","dateModified":"2022-08-16T20:30:42+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/statuts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/statuts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/statuts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Statuts"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_shortlink":"https:\/\/wp.me\/Pd7hzg-jo","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/pages\/1202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/comments?post=1202"}],"version-history":[{"count":3,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/pages\/1202\/revisions"}],"predecessor-version":[{"id":3807,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/pages\/1202\/revisions\/3807"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media?parent=1202"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/coauthors?post=1202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}