{"id":11512,"date":"2026-03-04T11:43:18","date_gmt":"2026-03-04T21:43:18","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=membre&#038;p=11512"},"modified":"2026-04-15T15:12:13","modified_gmt":"2026-04-16T01:12:13","slug":"serge-planes","status":"publish","type":"membre","link":"https:\/\/recherche.upf.pf\/fr\/membre\/serge-planes\/","title":{"rendered":"Serge Planes"},"content":{"rendered":"","protected":false},"author":272,"featured_media":12525,"template":"","coauthors":[525],"class_list":["post-11512","membre","type-membre","status-publish","has-post-thumbnail","hentry","position-directeur-de-recherche","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serge Planes &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/fr\/membre\/serge-planes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serge Planes &#8226; Recherche UPF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/membre\/serge-planes\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T01:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/03\/S-PLANES-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"183\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sophie Chaigne\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/\",\"name\":\"Serge Planes &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/S-PLANES-1.jpg\",\"datePublished\":\"2026-03-04T21:43:18+00:00\",\"dateModified\":\"2026-04-16T01:12:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/S-PLANES-1.jpg\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/S-PLANES-1.jpg\",\"width\":183,\"height\":183,\"caption\":\"splanes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/serge-planes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serge Planes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serge Planes &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/fr\/membre\/serge-planes\/","og_locale":"fr_FR","og_type":"article","og_title":"Serge Planes &#8226; Recherche UPF","og_url":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2026-04-16T01:12:13+00:00","og_image":[{"width":183,"height":183,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/03\/S-PLANES-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Written by":"Sophie Chaigne"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/","url":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/","name":"Serge Planes &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/03\/S-PLANES-1.jpg","datePublished":"2026-03-04T21:43:18+00:00","dateModified":"2026-04-16T01:12:13+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/membre\/serge-planes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/03\/S-PLANES-1.jpg","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/03\/S-PLANES-1.jpg","width":183,"height":183,"caption":"splanes"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/membre\/serge-planes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Serge Planes"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/membre\/11512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/membre"}],"about":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/types\/membre"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/users\/272"}],"version-history":[{"count":2,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/membre\/11512\/revisions"}],"predecessor-version":[{"id":11514,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/membre\/11512\/revisions\/11514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media\/12525"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media?parent=11512"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/coauthors?post=11512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}