{"id":11386,"date":"2026-02-05T14:19:51","date_gmt":"2026-02-06T00:19:51","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=evenement&#038;p=11386"},"modified":"2026-03-09T11:30:08","modified_gmt":"2026-03-09T21:30:08","slug":"les-conferences-de-la-recherche-2026","status":"publish","type":"evenement","link":"https:\/\/recherche.upf.pf\/fr\/evenement\/les-conferences-de-la-recherche-2026\/","title":{"rendered":"Les Conf\u00e9rences de la Recherche 2026"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organis\u00e9es par le <strong>Consortium RESIPOL<\/strong> dans le cadre de la politique de site de la Polyn\u00e9sie fran\u00e7aise, les Rencontres scientifiques annuelles constituent un temps fort de la recherche sur le territoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elles offrent aux chercheurs et enseignants-chercheurs l\u2019opportunit\u00e9 de mieux se conna\u00eetre, de pr\u00e9senter leurs travaux et de dialoguer avec l\u2019ensemble des acteurs du territoire : services du Pays et de l\u2019\u00c9tat, partenaires \u00e9conomiques et repr\u00e9sentants de la soci\u00e9t\u00e9 civile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 du partage des connaissances, cette manifestation vise \u00e0 <strong>structurer un dialogue durable entre recherche et soci\u00e9t\u00e9<\/strong>, afin d\u2019identifier des axes de collaboration innovants au service du d\u00e9veloppement scientifique, \u00e9conomique, social et environnemental de la Polyn\u00e9sie fran\u00e7aise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019<strong>Universit\u00e9 de la Polyn\u00e9sie fran\u00e7aise (UPF)<\/strong> y joue un r\u00f4le structurant, en mobilisant ses laboratoires pluridisciplinaires et en contribuant \u00e0 une approche int\u00e9gr\u00e9e et transversale des grands enjeux du territoire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Une th\u00e9matique au c\u0153ur des enjeux insulaires<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cette 8\u1d49 \u00e9dition portera sur :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab Sant\u00e9 des socio-\u00e9cosyst\u00e8mes et des populations dans un contexte de changements locaux et globaux \u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette th\u00e9matique met en lumi\u00e8re les liens \u00e9troits entre la sant\u00e9 humaine et celle des milieux naturels en Polyn\u00e9sie fran\u00e7aise, dans une perspective r\u00e9solument tourn\u00e9e vers l\u2019action.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle vise \u00e0 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Identifier, tester et d\u00e9ployer des <strong>r\u00e9ponses concr\u00e8tes<\/strong> pour r\u00e9duire les pressions locales ;<\/li>\n\n\n\n<li>Renforcer l\u2019adaptation aux changements globaux (urbanisation, pollution, surexploitation, esp\u00e8ces envahissantes, changement climatique) ;<\/li>\n\n\n\n<li>Promouvoir la pr\u00e9vention, la gestion durable des ressources et la restauration \u00e9cologique.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les travaux pr\u00e9sent\u00e9s mobiliseront les <strong>donn\u00e9es d\u2019observation, la mod\u00e9lisation et les outils d\u2019aide \u00e0 la d\u00e9cision<\/strong> afin d\u2019analyser les al\u00e9as et les vuln\u00e9rabilit\u00e9s (climat, littoral, milieux naturels) et de co-construire des trajectoires de r\u00e9silience adapt\u00e9es aux territoires insulaires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vers des trajectoires de r\u00e9silience<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9changes porteront \u00e9galement sur les strat\u00e9gies permettant de :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prot\u00e9ger et restaurer les \u00e9cosyst\u00e8mes cl\u00e9s (r\u00e9cifs, lagons, for\u00eats, zones humides) ;<\/li>\n\n\n\n<li>Suivre dans le temps l\u2019impact des actions mises en \u0153uvre ;<\/li>\n\n\n\n<li>Mieux comprendre les interactions soci\u00e9t\u00e9s\u2013milieux (pass\u00e9, pr\u00e9sent, futur).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019objectif est clair : <strong>am\u00e9liorer durablement la sant\u00e9 et le bien-\u00eatre des populations<\/strong>, en s\u00e9curisant l\u2019eau et l\u2019alimentation, en r\u00e9duisant les risques sanitaires, climatiques et environnementaux, en r\u00e9sorbant les in\u00e9galit\u00e9s de sant\u00e9 et en soutenant des modes de vie plus r\u00e9silients.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour suivre en direct les conf\u00e9rences : https:\/\/youtube.com\/live\/7MxJrWj4qEI?feature=share<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Version-finale-programme-conferences-de-la-Recherche-2026-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Version finale programme conf\u00e9rences de la Recherche 2026.\"><\/object><a id=\"wp-block-file--media-d2f55e4c-4366-4edc-9f22-fda989b35b83\" href=\"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/attachment\/version-finale-programme-conferences-de-la-recherche-2026-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Version finale programme conf\u00e9rences de la Recherche 2026<\/a><a href=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Version-finale-programme-conferences-de-la-Recherche-2026-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d2f55e4c-4366-4edc-9f22-fda989b35b83\">T\u00e9l\u00e9charger<\/a><\/div>","protected":false},"author":253,"featured_media":11483,"template":"","coauthors":[499],"class_list":["post-11386","evenement","type-evenement","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/fr\/evenement\/les-conferences-de-la-recherche-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"Organis\u00e9es par le Consortium RESIPOL dans le cadre de la politique de site de la Polyn\u00e9sie fran\u00e7aise, les Rencontres scientifiques annuelles constituent un temps fort de la recherche sur le territoire. Elles offrent aux chercheurs et enseignants-chercheurs l\u2019opportunit\u00e9 de mieux se conna\u00eetre, de pr\u00e9senter leurs travaux et de dialoguer avec l\u2019ensemble des acteurs du territoire&hellip; Continue reading Les Conf\u00e9rences de la Recherche 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T21:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Plan-de-travail-12-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1921\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Alice Enjalbal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/\",\"name\":\"Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Plan-de-travail-12-100.jpg\",\"datePublished\":\"2026-02-06T00:19:51+00:00\",\"dateModified\":\"2026-03-09T21:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Plan-de-travail-12-100.jpg\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Plan-de-travail-12-100.jpg\",\"width\":1921,\"height\":1081,\"caption\":\"affiche CDLR 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/evenement\\\/les-conferences-de-la-recherche-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/evenement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Conf\u00e9rences de la Recherche 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/fr\/evenement\/les-conferences-de-la-recherche-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF","og_description":"Organis\u00e9es par le Consortium RESIPOL dans le cadre de la politique de site de la Polyn\u00e9sie fran\u00e7aise, les Rencontres scientifiques annuelles constituent un temps fort de la recherche sur le territoire. Elles offrent aux chercheurs et enseignants-chercheurs l\u2019opportunit\u00e9 de mieux se conna\u00eetre, de pr\u00e9senter leurs travaux et de dialoguer avec l\u2019ensemble des acteurs du territoire&hellip; Continue reading Les Conf\u00e9rences de la Recherche 2026","og_url":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2026-03-09T21:30:08+00:00","og_image":[{"width":1921,"height":1081,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Plan-de-travail-12-100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes","Written by":"Alice Enjalbal"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/","url":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/","name":"Les Conf\u00e9rences de la Recherche 2026 &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Plan-de-travail-12-100.jpg","datePublished":"2026-02-06T00:19:51+00:00","dateModified":"2026-03-09T21:30:08+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Plan-de-travail-12-100.jpg","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2026\/02\/Plan-de-travail-12-100.jpg","width":1921,"height":1081,"caption":"affiche CDLR 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/evenement\/les-conferences-de-la-recherche-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements","item":"https:\/\/recherche.upf.pf\/fr\/evenement\/"},{"@type":"ListItem","position":3,"name":"Les Conf\u00e9rences de la Recherche 2026"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/evenement\/11386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/evenement"}],"about":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/types\/evenement"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/users\/253"}],"version-history":[{"count":9,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/evenement\/11386\/revisions"}],"predecessor-version":[{"id":11529,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/evenement\/11386\/revisions\/11529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media\/11483"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/media?parent=11386"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/coauthors?post=11386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}