{"id":7745,"date":"2023-11-30T11:58:56","date_gmt":"2023-11-30T21:58:56","guid":{"rendered":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/"},"modified":"2023-11-30T13:02:37","modified_gmt":"2023-11-30T23:02:37","slug":"matairea-cadousteau-2","status":"publish","type":"membre","link":"https:\/\/recherche.upf.pf\/en\/membre\/matairea-cadousteau-2\/","title":{"rendered":"Matairea Cadousteau"},"content":{"rendered":"","protected":false},"author":239,"featured_media":7747,"template":"","coauthors":[484],"class_list":["post-7745","membre","type-membre","status-publish","has-post-thumbnail","hentry","position-chercheur-autre","section_cnu-128","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matairea Cadousteau &#8226; Recherche UPF<\/title>\n<meta name=\"description\" content=\"Docteur en sciences de l&#039;\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/en\/membre\/matairea-cadousteau-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matairea Cadousteau &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"Docteur en sciences de l&#039;\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-30T23:02:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2023\/11\/IMG_1985.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matairea CADOUSTEAU\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/\",\"name\":\"Matairea Cadousteau &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1985.jpg\",\"datePublished\":\"2023-11-30T21:58:56+00:00\",\"dateModified\":\"2023-11-30T23:02:37+00:00\",\"description\":\"Docteur en sciences de l'\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1985.jpg\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/IMG_1985.jpg\",\"width\":720,\"height\":960,\"caption\":\"Observations de situations didactiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/matairea-cadousteau-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matairea Cadousteau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"University of French Polynesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matairea Cadousteau &#8226; Recherche UPF","description":"Docteur en sciences de l'\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/en\/membre\/matairea-cadousteau-2\/","og_locale":"en_US","og_type":"article","og_title":"Matairea Cadousteau &#8226; Recherche UPF","og_description":"Docteur en sciences de l'\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.","og_url":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2023-11-30T23:02:37+00:00","og_image":[{"width":720,"height":960,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2023\/11\/IMG_1985.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Written by":"Matairea CADOUSTEAU"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/","url":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/","name":"Matairea Cadousteau &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2023\/11\/IMG_1985.jpg","datePublished":"2023-11-30T21:58:56+00:00","dateModified":"2023-11-30T23:02:37+00:00","description":"Docteur en sciences de l'\u00e9ducation, repr\u00e9sentant des membres associ\u00e9s au conseil du laboratoire, Membre associ\u00e9 \u00e0 l\u2019\u00c9quipe de Didactique Clinique - Toulouse, r\u00e9f\u00e9rent du R\u00e9seau de Recherches Interdisciplinaires sur les Interactions entre Cultures, Langues et Apprentissages Scolaires (RIICLAS) en Polyn\u00e9sie fran\u00e7aise.","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2023\/11\/IMG_1985.jpg","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2023\/11\/IMG_1985.jpg","width":720,"height":960,"caption":"Observations de situations didactiques"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/membre\/matairea-cadousteau-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Matairea Cadousteau"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"University of French Polynesia","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/7745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre"}],"about":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/types\/membre"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/users\/239"}],"version-history":[{"count":3,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/7745\/revisions"}],"predecessor-version":[{"id":7749,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/7745\/revisions\/7749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media\/7747"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media?parent=7745"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/coauthors?post=7745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}