{"id":4322,"date":"2022-08-12T15:02:25","date_gmt":"2022-08-13T01:02:25","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=membre&#038;p=4322"},"modified":"2026-04-15T15:22:56","modified_gmt":"2026-04-16T01:22:56","slug":"vahine-ahuurua-rurua","status":"publish","type":"membre","link":"https:\/\/recherche.upf.pf\/en\/membre\/vahine-ahuurua-rurua\/","title":{"rendered":"Vahine Ahuurua Rurua"},"content":{"rendered":"","protected":false},"author":118,"featured_media":12535,"template":"","coauthors":[253,334],"class_list":["post-4322","membre","type-membre","status-publish","has-post-thumbnail","hentry","position-chercheuse-autre","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vahine Ahuurua Rurua &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/en\/membre\/vahine-ahuurua-rurua\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vahine Ahuurua Rurua &#8226; Recherche UPF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T01:22:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2022\/08\/V-RURUA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"presta, Vahine Rurua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/\",\"name\":\"Vahine Ahuurua Rurua &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/V-RURUA.jpg\",\"datePublished\":\"2022-08-13T01:02:25+00:00\",\"dateModified\":\"2026-04-16T01:22:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/V-RURUA.jpg\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/V-RURUA.jpg\",\"width\":225,\"height\":225,\"caption\":\"vrurua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/membre\\\/vahine-ahuurua-rurua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vahine Ahuurua Rurua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"University of French Polynesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vahine Ahuurua Rurua &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/en\/membre\/vahine-ahuurua-rurua\/","og_locale":"en_US","og_type":"article","og_title":"Vahine Ahuurua Rurua &#8226; Recherche UPF","og_url":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2026-04-16T01:22:56+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2022\/08\/V-RURUA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Written by":"presta, Vahine Rurua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/","url":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/","name":"Vahine Ahuurua Rurua &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2022\/08\/V-RURUA.jpg","datePublished":"2022-08-13T01:02:25+00:00","dateModified":"2026-04-16T01:22:56+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2022\/08\/V-RURUA.jpg","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2022\/08\/V-RURUA.jpg","width":225,"height":225,"caption":"vrurua"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/membre\/vahine-ahuurua-rurua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Vahine Ahuurua Rurua"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"University of French Polynesia","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/4322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre"}],"about":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/types\/membre"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":6,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/4322\/revisions"}],"predecessor-version":[{"id":11511,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/membre\/4322\/revisions\/11511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media\/12535"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media?parent=4322"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/coauthors?post=4322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}