{"id":10730,"date":"2025-09-10T09:08:10","date_gmt":"2025-09-10T19:08:10","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=appel-a-projets&#038;p=10730"},"modified":"2025-09-11T10:14:07","modified_gmt":"2025-09-11T20:14:07","slug":"bourses-de-mobilite","status":"publish","type":"appel-a-projets","link":"https:\/\/recherche.upf.pf\/en\/appel-a-projets\/bourses-de-mobilite\/","title":{"rendered":"Bourses de mobilit\u00e9"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/appel-a-projets\/10730\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p><p class=\"wp-block-paragraph\">Appel \u00e0 candidatures pour une bourse de mobilit\u00e9 pour des chercheurs n\u00e9o-z\u00e9landais collaborant avec la France sur des projets Horizon Europe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet appel s\u2019inscrit dans le cadre de l\u2019<strong>association de la Nouvelle-Z\u00e9lande \u00e0 Horizon Europe<\/strong>, qui ouvre de nouvelles perspectives de coop\u00e9ration et de co-financement entre \u00e9quipes n\u00e9o-z\u00e9landaises et fran\u00e7aises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;objectif de cette bourse est <strong>d&#8217;initier ou renforcer<\/strong> des collaborations de recherche en France \/  Nouvelle-Z\u00e9lande, de <strong>faciliter la pr\u00e9paration<\/strong> de projets conjoints Horizon Europe mais aussi de <strong>financer la mobilit\u00e9<\/strong> de chercheurs Neo-z\u00e9landais vers la France. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&#8217;h\u00e9sitez pas \u00e0 contacter l&#8217;adresse gestion-recherche@upf.pf<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.universitiesnz.ac.nz\/france-new-zealand-university-research-linkage\" style=\"padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\" target=\"_blank\" rel=\"noreferrer noopener\">Plus d&#8217;infos <\/a><\/div>\n<\/div>","protected":false},"author":253,"featured_media":0,"template":"","coauthors":[499],"class_list":["post-10730","appel-a-projets","type-appel-a-projets","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bourses de mobilit\u00e9  &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/en\/appel-a-projets\/bourses-de-mobilite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bourses de mobilit\u00e9  &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Fran\u00e7ais. Appel \u00e0 candidatures pour une bourse de mobilit\u00e9 pour des chercheurs n\u00e9o-z\u00e9landais collaborant avec la France sur des projets Horizon Europe Cet appel s\u2019inscrit dans le cadre de l\u2019association de la Nouvelle-Z\u00e9lande \u00e0 Horizon Europe, qui ouvre de nouvelles perspectives de coop\u00e9ration et de co-financement entre \u00e9quipes&hellip; Continue reading Bourses de mobilit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T20:14:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Alice Enjalbal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/appel-a-projets\\\/bourses-de-mobilite\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/appel-a-projets\\\/bourses-de-mobilite\\\/\",\"name\":\"Bourses de mobilit\u00e9  &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"datePublished\":\"2025-09-10T19:08:10+00:00\",\"dateModified\":\"2025-09-11T20:14:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/appel-a-projets\\\/bourses-de-mobilite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/appel-a-projets\\\/bourses-de-mobilite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/appel-a-projets\\\/bourses-de-mobilite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bourses de mobilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"University of French Polynesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bourses de mobilit\u00e9  &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/en\/appel-a-projets\/bourses-de-mobilite\/","og_locale":"en_US","og_type":"article","og_title":"Bourses de mobilit\u00e9  &#8226; Recherche UPF","og_description":"Sorry, this entry is only available in Fran\u00e7ais. Appel \u00e0 candidatures pour une bourse de mobilit\u00e9 pour des chercheurs n\u00e9o-z\u00e9landais collaborant avec la France sur des projets Horizon Europe Cet appel s\u2019inscrit dans le cadre de l\u2019association de la Nouvelle-Z\u00e9lande \u00e0 Horizon Europe, qui ouvre de nouvelles perspectives de coop\u00e9ration et de co-financement entre \u00e9quipes&hellip; Continue reading Bourses de mobilit\u00e9","og_url":"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2025-09-11T20:14:07+00:00","twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Est. reading time":"1 minute","Written by":"Alice Enjalbal"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/","url":"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/","name":"Bourses de mobilit\u00e9  &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"datePublished":"2025-09-10T19:08:10+00:00","dateModified":"2025-09-11T20:14:07+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/appel-a-projets\/bourses-de-mobilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"Bourses de mobilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"University of French Polynesia","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/appel-a-projets\/10730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/appel-a-projets"}],"about":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/types\/appel-a-projets"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/users\/253"}],"version-history":[{"count":2,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/appel-a-projets\/10730\/revisions"}],"predecessor-version":[{"id":10741,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/appel-a-projets\/10730\/revisions\/10741"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media?parent=10730"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/coauthors?post=10730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}