{"id":9450,"date":"2024-11-28T09:11:46","date_gmt":"2024-11-28T19:11:46","guid":{"rendered":"https:\/\/recherche.upf.pf\/?post_type=actualite&#038;p=9450"},"modified":"2024-11-28T09:11:49","modified_gmt":"2024-11-28T19:11:49","slug":"seminaire-gepasud-2024","status":"publish","type":"actualite","link":"https:\/\/recherche.upf.pf\/en\/actualite\/seminaire-gepasud-2024\/","title":{"rendered":"S\u00e9minaire GePaSUD 2024"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/recherche.upf.pf\/fr\/wp-json\/wp\/v2\/actualite\/9450\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p><p class=\"wp-block-paragraph\">Le 21 novembre 2024 une quarantaine de personnes ce sont r\u00e9unis pour le s\u00e9minaire annuel GEPASUD sur la <strong>R\u00e9silience en Territoire Insulaire Polyn\u00e9sien<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polyn\u00e9sie fran\u00e7aise est confront\u00e9e \u00e0 de nombreux d\u00e9fis en raison de sa situation g\u00e9ographique unique. Ce territoire, aussi vaste que l\u2019Europe, est constitu\u00e9 d\u2019une myriade de petites \u00eeles et d\u2019atolls, et doit r\u00e9pondre \u00e0 des besoins cruciaux : assurer son approvisionnement \u00e9nerg\u00e9tique, prot\u00e9ger ses ressources hydrologiques, marines, animales et v\u00e9g\u00e9tales, faire face \u00e0 des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames, et soutenir son tissu industriel et commercial local. Les enjeux \u00e9conomiques associ\u00e9s \u00e0 ces d\u00e9fis repr\u00e9sentent des milliards de francs pacifiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, les moyens dont dispose la Polyn\u00e9sie sont limit\u00e9s. Surveiller une zone aussi immense est financi\u00e8rement prohibitif pour un pays \u00e0 faibles revenus. De plus, la pr\u00e9diction locale de la disponibilit\u00e9 des ressources solaires, \u00e9oliennes et hydrologiques sur des zones \u00e9merg\u00e9es souvent plus petites que la r\u00e9solution des mod\u00e8les m\u00e9t\u00e9orologiques actuels reste impr\u00e9cise. Cela souligne la n\u00e9cessit\u00e9 de nouvelles approches. Par ailleurs, les besoins en recherche et d\u00e9veloppement (R&amp;D), ainsi qu&#8217;en surveillance environnementale, d\u00e9passent souvent les capacit\u00e9s locales, que ce soit pour le contr\u00f4le individuel des millions de perles de Tahiti export\u00e9es ou pour l\u2019analyse des millions de commentaires en ligne sur l\u2019exp\u00e9rience touristique.<br>N\u00e9anmoins, ces probl\u00e9matiques sont \u00e9troitement li\u00e9es, et le GEPASUD s\u2019efforce de coordonner et d\u2019organiser les recherches pour am\u00e9liorer cette situation. Son objectif est de proposer des solutions pratiques et accessibles, adapt\u00e9es aux contraintes sp\u00e9cifiques du territoire, tout en tenant compte des d\u00e9fis li\u00e9s au changement climatique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"author":253,"featured_media":9451,"template":"","coauthors":[499],"class_list":["post-9450","actualite","type-actualite","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recherche.upf.pf\/en\/actualite\/seminaire-gepasud-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Fran\u00e7ais. Le 21 novembre 2024 une quarantaine de personnes ce sont r\u00e9unis pour le s\u00e9minaire annuel GEPASUD sur la R\u00e9silience en Territoire Insulaire Polyn\u00e9sien. La Polyn\u00e9sie fran\u00e7aise est confront\u00e9e \u00e0 de nombreux d\u00e9fis en raison de sa situation g\u00e9ographique unique. Ce territoire, aussi vaste que l\u2019Europe, est constitu\u00e9&hellip; Continue reading S\u00e9minaire GePaSUD 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Recherche UPF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/univpf\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T19:11:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2024\/11\/image-900x900.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@univpf\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Alice Enjalbal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/\",\"name\":\"S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"datePublished\":\"2024-11-28T19:11:46+00:00\",\"dateModified\":\"2024-11-28T19:11:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"width\":1125,\"height\":1125,\"caption\":\"S\u00e9minaire GePaSUD\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/actualite\\\/seminaire-gepasud-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/recherche.upf.pf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9minaire GePaSUD 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"name\":\"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"description\":\"University of French Polynesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\"},\"alternateName\":\"Recherche UPF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#organization\",\"name\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"contentUrl\":\"https:\\\/\\\/recherche.upf.pf\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-UPF.png\",\"width\":2132,\"height\":968,\"caption\":\"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise\"},\"image\":{\"@id\":\"https:\\\/\\\/recherche.upf.pf\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/univpf\",\"https:\\\/\\\/x.com\\\/univpf\",\"https:\\\/\\\/www.instagram.com\\\/univpf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC535-cUv9j7pnLabFCFc17g\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recherche.upf.pf\/en\/actualite\/seminaire-gepasud-2024\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF","og_description":"Sorry, this entry is only available in Fran\u00e7ais. Le 21 novembre 2024 une quarantaine de personnes ce sont r\u00e9unis pour le s\u00e9minaire annuel GEPASUD sur la R\u00e9silience en Territoire Insulaire Polyn\u00e9sien. La Polyn\u00e9sie fran\u00e7aise est confront\u00e9e \u00e0 de nombreux d\u00e9fis en raison de sa situation g\u00e9ographique unique. Ce territoire, aussi vaste que l\u2019Europe, est constitu\u00e9&hellip; Continue reading S\u00e9minaire GePaSUD 2024","og_url":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/","og_site_name":"Recherche UPF","article_publisher":"https:\/\/www.facebook.com\/univpf","article_modified_time":"2024-11-28T19:11:49+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2024\/11\/image-900x900.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@univpf","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Alice Enjalbal"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/","url":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/","name":"S\u00e9minaire GePaSUD 2024 &#8226; Recherche UPF","isPartOf":{"@id":"https:\/\/recherche.upf.pf\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/#primaryimage"},"image":{"@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2024\/11\/image.png","datePublished":"2024-11-28T19:11:46+00:00","dateModified":"2024-11-28T19:11:49+00:00","breadcrumb":{"@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/#primaryimage","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2024\/11\/image.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2024\/11\/image.png","width":1125,"height":1125,"caption":"S\u00e9minaire GePaSUD"},{"@type":"BreadcrumbList","@id":"https:\/\/recherche.upf.pf\/actualite\/seminaire-gepasud-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/recherche.upf.pf\/"},{"@type":"ListItem","position":2,"name":"S\u00e9minaire GePaSUD 2024"}]},{"@type":"WebSite","@id":"https:\/\/recherche.upf.pf\/fr\/#website","url":"https:\/\/recherche.upf.pf\/fr\/","name":"Recherche - Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","description":"University of French Polynesia","publisher":{"@id":"https:\/\/recherche.upf.pf\/fr\/#organization"},"alternateName":"Recherche UPF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recherche.upf.pf\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recherche.upf.pf\/fr\/#organization","name":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise","url":"https:\/\/recherche.upf.pf\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","contentUrl":"https:\/\/recherche.upf.pf\/wp-content\/uploads\/2021\/02\/Logo-UPF.png","width":2132,"height":968,"caption":"Universit\u00e9 de la Polyn\u00e9sie Fran\u00e7aise"},"image":{"@id":"https:\/\/recherche.upf.pf\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/univpf","https:\/\/x.com\/univpf","https:\/\/www.instagram.com\/univpf\/","https:\/\/www.linkedin.com\/school\/universit\u00e9-de-la-polyn\u00e9sie-fran\u00e7aise\/","https:\/\/www.youtube.com\/channel\/UC535-cUv9j7pnLabFCFc17g","https:\/\/fr.wikipedia.org\/wiki\/Universit\u00e9_de_la_Polyn\u00e9sie_fran\u00e7aise"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/actualite\/9450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/actualite"}],"about":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/types\/actualite"}],"author":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/users\/253"}],"version-history":[{"count":2,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/actualite\/9450\/revisions"}],"predecessor-version":[{"id":9456,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/actualite\/9450\/revisions\/9456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media\/9451"}],"wp:attachment":[{"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/media?parent=9450"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/recherche.upf.pf\/en\/wp-json\/wp\/v2\/coauthors?post=9450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}